{"id":6705,"date":"2022-11-02T15:03:27","date_gmt":"2022-11-02T15:03:27","guid":{"rendered":"https:\/\/zenloop1.wpengine.com\/en\/?page_id=6705"},"modified":"2026-05-22T12:51:46","modified_gmt":"2026-05-22T12:51:46","slug":"pricing","status":"publish","type":"page","link":"https:\/\/www.zenloop.com\/en\/pricing\/","title":{"rendered":"Pricing"},"content":{"rendered":"<section         class=\"block-hero  no-margin padding-both\" style=\"background-image:url('');\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t\n\t\t\n\t\t<div class=\"grid \" style=\"grid-template-columns:1fr 1fr\">\n\t\t\t<div class=\"col flex-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h1>Pricing \u2014 Packages Built Around Your CX Stack<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p >zenloop offers a range of pricing packages to fit every budget and need. Start your CX Action Management journey today by requesting a free consultation!<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col flex-center image-side \">\n\t\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8638 size-full\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-White-DE-Hellen-Contact-section.png\" alt=\"\" width=\"916\" height=\"788\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-White-DE-Hellen-Contact-section.png 916w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-White-DE-Hellen-Contact-section-300x258.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-White-DE-Hellen-Contact-section-768x661.png 768w\" sizes=\"auto, (max-width: 916px) 100vw, 916px\" \/><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n<\/section>\n\n<section         class=\"block-columns  no-margin padding-bottom\" style=\"background-color:#ffffff;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t\n\t\t\t\t\n\t\t<div class=\"grid\" style=\"grid-template-columns:\trepeat( 1, 1fr)\">\t\t\t\t\n\t\t\t\t<div class=\"col \">\n\t\t\t\t\t<h2 class=\"pricinghead\">Package Overview<\/h2>\n<p class=\"pricingsub\">From small businesses starting with a few digital touchpoints, to growing companies looking to scale CX operations, to industry leaders with thousands of digital and non-digital touchpoints across a complex customer journey &#8211; zenloop offers suitable packages for all companies.<\/p>\n<section class=\"pricing\">\n<div class=\"planContainer\">\n<div class=\"plan\">\n<div class=\"titleContainer\" style=\"background-color: #fff5dc!important\">\n<div class=\"title\">Start<\/div>\n<div class=\"price\">\n        <span>Great for traditional SMBs starting their CX journey.<\/span>\n      <\/div>\n<\/p><\/div>\n<div class=\"infoContainer\">\n<ul class=\"features\">\n<li><strong>\u2022 Unlimited <\/strong> Surveys <\/li>\n<li><strong>\u2022 Unlimited <\/strong> Users <\/li>\n<li><strong>\u2022 25,000 <\/strong> Responses included <\/li>\n<li><strong>\u2022 1<\/strong> Team included <\/li>\n<li><strong>\u2022 Dedicated <\/strong> Onboarding Team<\/li>\n<li><strong>\u2022 Quarterly <\/strong> Business Reviews<\/li>\n<hr class=\"hrpricing\">\n<li>\u2022 Standard Data Collection<\/li>\n<li>\u2022 2 Topic Levels<\/li>\n<li>\u2022 Basic Dashboards and Reports<\/li>\n<li>\u2022 Standard User Roles<\/li>\n<li>\u2022 Collect Feedback via Plug&amp;Play Integrations<\/li>\n<li>\u2022 Act Workflows via Plug&amp;Play<br \/>\n         <span style=\"color:#ffffff\">A<\/span> Integrations<\/li>\n<li>\u2022 Automated Text and Sentiment<br \/>\n        <span style=\"color:#ffffff\">A<\/span> Analysis<\/li>\n<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4.9rem;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n<\/ul>\n<p><a class=\"selectPlan\" href=\"#getstarted\">Get Started<\/a>\n    <\/div>\n<\/p><\/div>\n<div class=\"plan\">\n<div class=\"titleContainer\" style=\"background-color: #ffe5a7!important\">\n<div class=\"title\">Grow<\/div>\n<div class=\"price\">\n        <span>Ideal for international businesses scaling and automating CX Ops.<\/span>\n      <\/div>\n<\/p><\/div>\n<div class=\"infoContainer\">\n<ul class=\"features\">\n<li><strong>\u2022 Unlimited <\/strong> Surveys <\/li>\n<li><strong>\u2022 Unlimited <\/strong> Users <\/li>\n<li><strong>\u2022 200,000 <\/strong> Responses included <\/li>\n<li><strong>\u2022 2<\/strong> Teams included<\/li>\n<li><strong>\u2022 Dedicated <\/strong> Onboarding Team<\/li>\n<li><strong>\u2022 Bi-Monthly<\/strong> Business Reviews<\/li>\n<hr class=\"hrpricing\">\n<li>Everything included in <strong>Start<\/strong> plus:<\/li>\n<li>\u2022 Collect Feedback via Premium Integrations<\/li>\n<li>\u2022 Act Workflows via Premium<br \/>\n        <span style=\"color:#ffffff\">A<\/span> Integrations<\/li>\n<li>\u2022 Access to API<\/li>\n<li>\u2022 4 Topic Levels<\/li>\n<li>\u2022 Advanced Dashboards &amp; Reports<\/li>\n<li>\u2022 Advanced Analytics Engine:<br \/>\n        <span style=\"color:#ffffff\">a<\/span> Translations<\/li>\n<li>\u2022 Data Access by Survey <\/li>\n<li>\u2022 Dedicated Success Manager <\/li>\n<\/ul>\n<p><a class=\"selectPlan\" href=\"#getstarted\">Get Started<\/a>\n    <\/div>\n<\/p><\/div>\n<div class=\"plan\">\n<div class=\"titleContainer\" style=\"background-color: #ffd87c!important\">\n<div class=\"title\">Lead<\/div>\n<div class=\"price\">\n        <span>Best for large companies with a complex customer journey.<\/span>\n      <\/div>\n<\/p><\/div>\n<div class=\"infoContainer\">\n<ul class=\"features\">\n<li><strong>\u2022 Unlimited <\/strong> Surveys <\/li>\n<li><strong>\u2022 Unlimited <\/strong> Users <\/li>\n<li><strong>\u2022 300,000 <\/strong> Responses included <\/li>\n<li><strong>\u2022 3<\/strong> Teams included<\/li>\n<li><strong>\u2022 Dedicated <\/strong> Onboarding Team<\/li>\n<li><strong>\u2022 Monthly<\/strong> Business Reviews<\/li>\n<hr class=\"hrpricing\">\n<li>Everything included in <strong>Grow<\/strong> plus:<\/li>\n<li>\u2022 Advanced Organizational <span style=\"color:#ffffff\">A<\/span>Management<\/li>\n<li>\u2022 Custom User Roles<\/li>\n<li>\u2022 Single Sign On (SSO)<\/li>\n<li>\u2022 White Label Surveys<\/li>\n<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 13rem;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n<\/ul>\n<p><a class=\"selectPlan\" href=\"#getstarted\">Get Started<\/a>\n    <\/div>\n<\/p><\/div>\n<\/div>\n<\/section>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\n\t<\/div>\n<\/section>\n\n<section         class=\"block-scores  no-margin custom\" style=\"background-image:url('');padding-top:-30px;padding-bottom:120px;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t<h2 class=\"section-title\">Top Scores for zenloop<\/h2>\n\t\t\t\t<div class=\"grid scores\" style=\"grid-template-columns:1fr 1fr 1fr 1fr 1fr 1fr\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/trustpilot-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.3 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star uncheck\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/capterra-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.9 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/getapp-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.9 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/financesonline-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.0 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star uncheck\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/google-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">5 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/g2-crowd-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.8 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section         class=\"block-registration  no-margin padding-both\" style=\"background-image:url('');\" id=\"getstarted\"\n>\n\t<div class=\"container\">\n\t\t<h2 class=\"section-title\">Request a Free Online Consultation<\/h2>\t\t<div class=\"row\">\n\t\t\t<div class=\"six columns\">\n\t\t\t\t<div class=\"description\"><h4>Discover all the benefits zenloop offers<\/h4>\n<\/div>\n\t\t\t\t<div class=\"grid\" style=\"grid-template-columns:2.5rem 1fr;grid-gap:1.25rem;\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-intelligence-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-intelligence-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-intelligence-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Individually measure customer experiences at all touchpoints along the entire customer journey.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-centricity-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-centricity-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-centricity-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Real-time analysis and aggregated reports allow identifying the causes for dissatisfied customers.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/continous-innovation-zenloop-keyvisual-2.png\" class=\"attachment-full size-full\" alt=\"continous-innovation-zenloop-keyvisual\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/continous-innovation-zenloop-keyvisual-2.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/continous-innovation-zenloop-keyvisual-2-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Bring real-time customer feedback into your organization and build a customer-centric culture.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/retain-at-scale-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/retain-at-scale-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/retain-at-scale-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Recognize dissatisfied, churning customers and win them back in an automated, personalized way.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/brand-advocacy-zenloop-keyvisual-1.png\" class=\"attachment-full size-full\" alt=\"brand-advocacy-zenloop-keyvisual\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/brand-advocacy-zenloop-keyvisual-1.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/brand-advocacy-zenloop-keyvisual-1-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Leverage the potential of loyal customers for free referrals and improving your online reputation.<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"six columns\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"registration\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1990-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1990\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/6705#wpcf7-f1990-o1\" method=\"post\" class=\"wpcf7-form init demo\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1990\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1990-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>First Name<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"first_name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Last Name<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last_name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Company<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-relative six columns\">\n\t\t<p><label> Job title<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"job_title\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"job_title\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Business Email Address<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"business_email_address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"business_email_address\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Business Phone Number<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone_number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"phone_number\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<p><label>Leave us a comment<\/label>\n\t<\/p>\n\t<div class=\"form-relative twelve columns\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"comment\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"comment\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div style=\"display: none\">\n\t<p><span class=\"wpcf7-form-control-wrap initialTrafficSource\" data-name=\"initialTrafficSource\"><input type=\"text\" name=\"initialTrafficSource\" class=\"wpcf7-form-control wpcf7-text wpcf7dtx wpcf7dtx-text dtx-pageload\" aria-invalid=\"false\" readonly=\"readonly\" data-dtx-value=\"CF7_get_cookie%20key%3D%27initialTrafficSource%27\"><\/span>\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Talk to Us\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"registration-confirmation\">\n\t\t\t\t\t<h3>Thank you for Your Interest!<\/h3>\n<p>Our CX experts will get in touch with you shortly.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":1504,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Pricing and Packages for VoC, NPS & Review Management%%page%% %%sep%% %%sitename%%","_yoast_wpseo_metadesc":"Module-based pricing for zenloop's CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.","_yoast_wpseo_meta-robots-noindex":"","inline_featured_image":false,"footnotes":""},"class_list":["post-6705","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pricing and Packages for VoC, NPS &amp; Review Management - zenloop<\/title>\n<meta name=\"description\" content=\"Module-based pricing for zenloop&#039;s CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zenloop.com\/en\/pricing\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pricing\" \/>\n<meta property=\"og:description\" content=\"Module-based pricing for zenloop&#039;s CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zenloop.com\/en\/pricing\/\" \/>\n<meta property=\"og:site_name\" content=\"zenloop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zenloop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T12:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/article-promoters-preview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@zenloophq\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/pricing\\\/\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/pricing\\\/\",\"name\":\"Pricing and Packages for VoC, NPS & Review Management - zenloop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/pricing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/pricing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/final-header-eNPS-Graphic.svg\",\"datePublished\":\"2022-11-02T15:03:27+00:00\",\"dateModified\":\"2026-05-22T12:51:46+00:00\",\"description\":\"Module-based pricing for zenloop's CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zenloop.com\\\/en\\\/pricing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/pricing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/final-header-eNPS-Graphic.svg\",\"contentUrl\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/final-header-eNPS-Graphic.svg\",\"width\":445,\"height\":345},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/\",\"name\":\"zenloop\",\"description\":\"Customer Experience Management and Action Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#organization\",\"name\":\"zenloop\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"contentUrl\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"width\":338,\"height\":104,\"caption\":\"zenloop\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zenloop\\\/\",\"https:\\\/\\\/x.com\\\/zenloophq\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zenloop\",\"https:\\\/\\\/www.instagram.com\\\/zenloophq\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pricing and Packages for VoC, NPS & Review Management - zenloop","description":"Module-based pricing for zenloop's CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zenloop.com\/en\/pricing\/","og_locale":"en_US","og_type":"article","og_title":"Pricing","og_description":"Module-based pricing for zenloop's CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.","og_url":"https:\/\/www.zenloop.com\/en\/pricing\/","og_site_name":"zenloop","article_publisher":"https:\/\/www.facebook.com\/zenloop\/","article_modified_time":"2026-05-22T12:51:46+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/article-promoters-preview.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@zenloophq","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zenloop.com\/en\/pricing\/","url":"https:\/\/www.zenloop.com\/en\/pricing\/","name":"Pricing and Packages for VoC, NPS & Review Management - zenloop","isPartOf":{"@id":"https:\/\/www.zenloop.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zenloop.com\/en\/pricing\/#primaryimage"},"image":{"@id":"https:\/\/www.zenloop.com\/en\/pricing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/final-header-eNPS-Graphic.svg","datePublished":"2022-11-02T15:03:27+00:00","dateModified":"2026-05-22T12:51:46+00:00","description":"Module-based pricing for zenloop's CX platform. Combine surveys, review monitoring and AI analysis. EU-hosted, GDPR-compliant. Talk to sales for a quote.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zenloop.com\/en\/pricing\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zenloop.com\/en\/pricing\/#primaryimage","url":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/final-header-eNPS-Graphic.svg","contentUrl":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/final-header-eNPS-Graphic.svg","width":445,"height":345},{"@type":"WebSite","@id":"https:\/\/www.zenloop.com\/en\/#website","url":"https:\/\/www.zenloop.com\/en\/","name":"zenloop","description":"Customer Experience Management and Action Management","publisher":{"@id":"https:\/\/www.zenloop.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zenloop.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zenloop.com\/en\/#organization","name":"zenloop","url":"https:\/\/www.zenloop.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zenloop.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","contentUrl":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","width":338,"height":104,"caption":"zenloop"},"image":{"@id":"https:\/\/www.zenloop.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zenloop\/","https:\/\/x.com\/zenloophq","https:\/\/www.linkedin.com\/company\/zenloop","https:\/\/www.instagram.com\/zenloophq\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages\/6705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/comments?post=6705"}],"version-history":[{"count":0,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages\/6705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/media\/1504"}],"wp:attachment":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/media?parent=6705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}