{"id":1749,"date":"2022-03-17T12:14:13","date_gmt":"2022-03-17T12:14:13","guid":{"rendered":"http:\/\/yhs.uyx.mybluehost.me\/en\/?page_id=1749"},"modified":"2024-07-22T09:12:05","modified_gmt":"2024-07-22T09:12:05","slug":"delight-customers","status":"publish","type":"page","link":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/","title":{"rendered":"Delight &#038; Close the Loop"},"content":{"rendered":"<section         class=\"block-hero  no-margin padding-both\" style=\"background-image:url('');\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t\n\t\t\n\t\t<div class=\"grid \" style=\"grid-template-columns:1fr 1fr\">\n\t\t\t<div class=\"col flex-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h1>Delight Customers and Close the Loop<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p >Wow your customers by letting them know their valuable feedback led to real action.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"buttons\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/request-demo\" class=\"button\">Get Started<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col flex-center image-side \">\n\t\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8644 size-full\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-product-page-5.jpg\" alt=\"\" width=\"916\" height=\"788\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-product-page-5.jpg 916w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-product-page-5-300x258.jpg 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/03\/Web-Image-product-page-5-768x661.jpg 768w\" sizes=\"auto, (max-width: 916px) 100vw, 916px\" \/><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n<\/section>\n\n<link rel=\"stylesheet\" type=\"text\/css\" href=\"\/\/cdn.jsdelivr.net\/npm\/slick-carousel@1.8.1\/slick\/slick.css\"\/>\n<script type=\"text\/javascript\" src=\"\/\/cdn.jsdelivr.net\/npm\/slick-carousel@1.8.1\/slick\/slick.min.js\"><\/script>\n\n<section         class=\"block-slider blue-split no-margin padding-top\" style=\"background-image:url('');\" id=\"\"\n>\t\n\t\t<div class=\"container\">\n            <div class=\"image-slider desktop\">\n\t\t\t\t\t\t\t\t\t<div class=\"slide\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2340\" height=\"1250\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight.png 2340w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight-300x160.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight-1024x547.png 1024w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight-768x410.png 768w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight-1536x821.png 1536w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Delight-2048x1094.png 2048w\" sizes=\"auto, (max-width: 2340px) 100vw, 2340px\" \/>                    <\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2340\" height=\"1250\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses.png 2340w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses-300x160.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses-1024x547.png 1024w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses-768x410.png 768w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses-1536x821.png 1536w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Responses-2048x1094.png 2048w\" sizes=\"auto, (max-width: 2340px) 100vw, 2340px\" \/>                    <\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2340\" height=\"1250\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2.png 2340w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2-300x160.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2-1024x547.png 1024w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2-768x410.png 768w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2-1536x821.png 1536w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Data_2-2048x1094.png 2048w\" sizes=\"auto, (max-width: 2340px) 100vw, 2340px\" \/>                    <\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2340\" height=\"1250\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers.png 2340w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers-300x160.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers-1024x547.png 1024w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers-768x410.png 768w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers-1536x821.png 1536w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2023\/03\/zenloop-Drivers-2048x1094.png 2048w\" sizes=\"auto, (max-width: 2340px) 100vw, 2340px\" \/>                    <\/div>\n\t\t\t\t\t\t\t <\/div>\n\n\t\t\t <div class=\"image-slider mobile\">\n\t\t\t\t\t\t\t\t\t<div class=\"slide\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"482\" height=\"760\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop-mobile-labels.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop-mobile-labels.png 482w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop-mobile-labels-190x300.png 190w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/>                    <\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"slide\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"482\" height=\"760\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop-mobile-answers-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop-mobile-answers-1.png 482w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop-mobile-answers-1-190x300.png 190w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/>                    <\/div>\n\t\t\t\t\t\t\t <\/div>\n\t\t<\/div>\n<\/section>\n\n<section         class=\"block-columns  margin-bottom small-padding-top\" style=\"background-image:url('');color:#02193c;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t\n\t\t\t\t\n\t\t<div class=\"grid\" style=\"grid-template-columns:\trepeat( 1, 1fr)\">\t\t\t\t\n\t\t\t\t<div class=\"col centered\">\n\t\t\t\t\t<h2 style=\"text-align: center\">Turn Customers Into True Fans<\/h2>\n<p style=\"text-align: center\">Ensure your customers know their voices are heard and inform them about initiatives triggered by their feedback.<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 40px;border-top-width:0px;border-bottom-width:0px;\"><\/span><\/p>\n<p style=\"text-align: center\"><a class=\"button\" href=\"https:\/\/www.zenloop.com\/en\/request-demo\">Talk to Us<\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\n\t<\/div>\n<\/section>\n\n<section         class=\"block-features  no-margin padding-both\" style=\"background-color:#02193c;color:#ffffff;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t<h2 class=\"section-title\">Closing the Loop With Action Management<\/h2>\t\t<div class=\"grid\" style=\"grid-template-columns:\t1fr\">\n\t\t<div class=\"grid features\" style=\"grid-template-columns:repeat(3, 1fr);grid-gap: 0 30px;\">\n\t\t\t\t\t<a class=\"col feature \" >\n\t\t\t\t<i class=\"block__icon fal fa-comment icon\"><\/i>\n\t\t\t\t<h5>Establish a Continuous Dialogue With Your Customers<\/h5>\n\t\t\t\t\t\t\t\t<div class=\"description \">Don\u2019t miss an opportunity to maximize customer loyalty by sharing the success of all initiatives born from their feedback.<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<a class=\"col feature \" >\n\t\t\t\t<i class=\"block__icon fal fa-chart-bar icon\"><\/i>\n\t\t\t\t<h5>Incentivize Additional Feedback and Reviews<\/h5>\n\t\t\t\t\t\t\t\t<div class=\"description \">Showing their input has a genuine impact motivates customers to provide even more precious feedback and reviews for your business.<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<a class=\"col feature \" >\n\t\t\t\t<i class=\"block__icon fal fa-rocket icon\"><\/i>\n\t\t\t\t<h5>Circulate Internal Delight Amongst Employees<\/h5>\n\t\t\t\t\t\t\t\t<div class=\"description \">Share wins internally to show your activities&#8217; impact on business goals. Build a customer-obsessed culture by motivating your teams with live updates. <\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n<\/section>\n\n<link rel=\"stylesheet\" type=\"text\/css\" href=\"\/\/cdn.jsdelivr.net\/npm\/slick-carousel@1.8.1\/slick\/slick.css\"\/>\n<script type=\"text\/javascript\" src=\"\/\/cdn.jsdelivr.net\/npm\/slick-carousel@1.8.1\/slick\/slick.min.js\"><\/script>\n\n<section         class=\"block-success-stories  no-margin padding-both\" style=\"background-image:url('');color:#02193c;\" id=\"\"\n>\t\n\t\t<div class=\"container\">\n\t\t\t<h2 class=\"section-title\">Our Customer Success Stories<\/h2>          \t<div class=\"success-stories\">\n\t\t\t\t\t\t\t\t\t<div class=\"success-story table\">\n\t\t\t\t\t\t<div class=\"left-side\" style=\"background-image:url('https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/keller-lynn-hoblitz-desktop.jpg')\"><\/div>\n\t\t\t\t\t\t<div class=\"right-side\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"72\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/08\/quote-slider-logo-keller.svg\" class=\"attachment-full size-full\" alt=\"logo of keller\" \/>\t\t\t\t\t\t\t<h4>Free Referral Marketing<\/h4>\n\t\t\t\t\t\t\t<div class=\"quote\">\n\t\t\t\t\t\t\t\t&#8220;We use the promoters as a free marketing channel, e.g. for our refer-a-friend program, but also to receive referrals on rating portals.&#8221;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<h6 class=\"author\">Lynn Hoblitz \/ KELLER Group GmbH<\/h6>\n\t\t\t\t\t\t\t<div class=\"position\">Manager CRM and Communications<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/section>\n\n<section         class=\"block-registration  no-margin padding-both\" style=\"background-image:url('');color:#02193c;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t<h2 class=\"section-title\">Turn Customers Into Partners and Fans. Share Success Internally to Prioritize Your CX Initiatives.<\/h2>\t\t<div class=\"row\">\n\t\t\t<div class=\"six columns\">\n\t\t\t\t<div class=\"description\"><h5 class=\"mb-2\">Let Us Show You How Action Management Pioneers Use zenloop to Create Customer-Centric Cultures<\/h5>\n<\/div>\n\t\t\t\t<div class=\"grid\" style=\"grid-template-columns:2.5rem 1fr;grid-gap:1.25rem;\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-intelligence-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-intelligence-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-intelligence-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Measure customer experiences at all touchpoints along the entire customer journey.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/continous-innovation-zenloop-keyvisual-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/continous-innovation-zenloop-keyvisual-1.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/continous-innovation-zenloop-keyvisual-1-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Identify and prioritize the key drivers of satisfaction and dissatisfaction.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-centricity-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-centricity-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/customer-centricity-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Bring real-time customer feedback into your organization and build a customer-centric culture.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/retain-at-scale-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/retain-at-scale-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/retain-at-scale-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Automatically trigger tailored win-back and advocacy programs at scale.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"col\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/brand-advocacy-zenloop-keyvisual.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/brand-advocacy-zenloop-keyvisual.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/brand-advocacy-zenloop-keyvisual-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"col\">Grow your online reputation with more positive reviews and referrals<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"six columns\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"registration\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1990-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1990\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1749#wpcf7-f1990-o1\" method=\"post\" class=\"wpcf7-form init demo\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1990\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1990-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>First Name<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"first_name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Last Name<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last_name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Company<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-relative six columns\">\n\t\t<p><label> Job title<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"job_title\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"job_title\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Business Email Address<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"business_email_address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"business_email_address\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-relative six columns\">\n\t\t<p><label>Business Phone Number<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone_number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"phone_number\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<p><label>Leave us a comment<\/label>\n\t<\/p>\n\t<div class=\"form-relative twelve columns\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"comment\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"comment\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div style=\"display: none\">\n\t<p><span class=\"wpcf7-form-control-wrap initialTrafficSource\" data-name=\"initialTrafficSource\"><input type=\"text\" name=\"initialTrafficSource\" class=\"wpcf7-form-control wpcf7-text wpcf7dtx wpcf7dtx-text dtx-pageload\" aria-invalid=\"false\" readonly=\"readonly\" data-dtx-value=\"CF7_get_cookie%20key%3D%27initialTrafficSource%27\"><\/span>\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Talk to Us\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"registration-confirmation\">\n\t\t\t\t\t<h3>Thank you for Your Interest!<\/h3>\n<p>Our CX experts will get in touch with you shortly.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section         class=\"block-columns  no-margin padding-both\" style=\"background-image:url('');color:#02193c;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t\n\t\t\t\t\n\t\t<div class=\"grid\" style=\"grid-template-columns:\trepeat( 2, 1fr)\">\t\t\t\t\n\t\t\t\t<div class=\"col flex-center\">\n\t\t\t\t\t<h2>Translate Customers Insights Into Innovation Using Our CX Action Management Platform<\/h2>\n<p>Let our CX experts show you how Action Management can transform your CX operations through intelligent workflows &#8211; turning your customers into real fans. Schedule a free consultation to see how our Action Management System and Platform can work for you.<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 40px;border-top-width:0px;border-bottom-width:0px;\"><\/span><\/p>\n<p><a class=\"button\" href=\"https:\/\/www.zenloop.com\/en\/request-demo\">Your Free CX Consultation<\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"col align-center\">\n\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8780 size-full\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Group-5-1.png\" alt=\"\" width=\"416\" height=\"416\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Group-5-1.png 416w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Group-5-1-300x300.png 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2024\/07\/Group-5-1-150x150.png 150w\" sizes=\"auto, (max-width: 416px) 100vw, 416px\" \/><\/p>\n<p style=\"text-align: center\">\u201cNo one said it would be easy \u2013 but with zenloop it actually is.\u201d<\/p>\n<p style=\"text-align: center\">Lisa Rentrop, CEO<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\n\t<\/div>\n<\/section>\n\n<section         class=\"block-scores  no-margin padding-both\" style=\"background-color:#ecedef;color:#02193c;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t<h2 class=\"section-title\">Top Scores for zenloop<\/h2>\n\t\t\t\t<div class=\"grid scores\" style=\"grid-template-columns:1fr 1fr 1fr 1fr 1fr 1fr\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/trustpilot-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.3 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star uncheck\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/capterra-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.9 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/getapp-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.9 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/financesonline-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.0 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star uncheck\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/google-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">5 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"32\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/g2-crowd-zenloop-review.svg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"rating\">4.8 \/ 5<\/div>\n\t\t\t\t\t\t<div class=\"stars\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/toast\/assets\/images\/star-full.svg\" class=\"star \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section         class=\"block-columns  no-margin padding-top\" style=\"background-color:#ffffff;color:#02193c;\" id=\"\"\n>\n\t<div class=\"container\">\n\t\t\n\t\t\t\t\n\t\t<div class=\"grid\" style=\"grid-template-columns:\t7fr 5fr\">\t\t\t\t\n\t\t\t\t<div class=\"col \">\n\t\t\t\t\t<h2 class=\"demo-module__headline h2\">Act on Feedback and Delight Customers With zenloop<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 40px;border-top-width:0px;border-bottom-width:0px;\"><\/span><\/h2>\n<p><a class=\"button\" href=\"https:\/\/www.zenloop.com\/en\/request-demo\">Get Started<\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"col \">\n\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1431\" src=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/2022\/03\/person_white_bg-e1647443728944.jpg\" alt=\"\" width=\"450\" height=\"364\" srcset=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/person_white_bg-e1647443728944.jpg 940w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/person_white_bg-e1647443728944-300x243.jpg 300w, https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/03\/person_white_bg-e1647443728944-768x622.jpg 768w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\n\t<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2964,"parent":961,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":true,"_yoast_wpseo_title":"Delight Customers | Platform","_yoast_wpseo_metadesc":"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.","_yoast_wpseo_meta-robots-noindex":"","inline_featured_image":false,"footnotes":""},"class_list":["post-1749","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Delight Customers | Platform<\/title>\n<meta name=\"description\" content=\"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delight &amp; Close the Loop\" \/>\n<meta property=\"og:description\" content=\"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/\" \/>\n<meta property=\"og:site_name\" content=\"zenloop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zenloop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T09:12:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png\" \/>\n\t<meta property=\"og:image:width\" content=\"338\" \/>\n\t<meta property=\"og:image:height\" content=\"104\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@zenloophq\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/\",\"name\":\"Delight Customers | Platform\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"datePublished\":\"2022-03-17T12:14:13+00:00\",\"dateModified\":\"2024-07-22T09:12:05+00:00\",\"description\":\"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"contentUrl\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"width\":338,\"height\":104},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/delight-customers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Platform\",\"item\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/platform\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delight &#038; Close the Loop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/\",\"name\":\"zenloop\",\"description\":\"Customer Experience Management and Action Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#organization\",\"name\":\"zenloop\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"contentUrl\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/zenloop.png\",\"width\":338,\"height\":104,\"caption\":\"zenloop\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zenloop.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zenloop\\\/\",\"https:\\\/\\\/x.com\\\/zenloophq\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zenloop\",\"https:\\\/\\\/www.instagram.com\\\/zenloophq\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Delight Customers | Platform","description":"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/","og_locale":"en_US","og_type":"article","og_title":"Delight & Close the Loop","og_description":"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.","og_url":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/","og_site_name":"zenloop","article_publisher":"https:\/\/www.facebook.com\/zenloop\/","article_modified_time":"2024-07-22T09:12:05+00:00","og_image":[{"width":338,"height":104,"url":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@zenloophq","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/","url":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/","name":"Delight Customers | Platform","isPartOf":{"@id":"https:\/\/www.zenloop.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/#primaryimage"},"image":{"@id":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","datePublished":"2022-03-17T12:14:13+00:00","dateModified":"2024-07-22T09:12:05+00:00","description":"Leverage the potential of loyal customers for referrals and delight returning customers by improving your online reputation with zenloop.","breadcrumb":{"@id":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/#primaryimage","url":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","contentUrl":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","width":338,"height":104},{"@type":"BreadcrumbList","@id":"https:\/\/www.zenloop.com\/en\/platform\/delight-customers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Platform","item":"https:\/\/www.zenloop.com\/en\/platform\/"},{"@type":"ListItem","position":2,"name":"Delight &#038; Close the Loop"}]},{"@type":"WebSite","@id":"https:\/\/www.zenloop.com\/en\/#website","url":"https:\/\/www.zenloop.com\/en\/","name":"zenloop","description":"Customer Experience Management and Action Management","publisher":{"@id":"https:\/\/www.zenloop.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zenloop.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zenloop.com\/en\/#organization","name":"zenloop","url":"https:\/\/www.zenloop.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zenloop.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","contentUrl":"https:\/\/www.zenloop.com\/en\/wp-content\/uploads\/sites\/2\/2022\/04\/zenloop.png","width":338,"height":104,"caption":"zenloop"},"image":{"@id":"https:\/\/www.zenloop.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zenloop\/","https:\/\/x.com\/zenloophq","https:\/\/www.linkedin.com\/company\/zenloop","https:\/\/www.instagram.com\/zenloophq\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages\/1749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/comments?post=1749"}],"version-history":[{"count":0,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages\/1749\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/pages\/961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/media\/2964"}],"wp:attachment":[{"href":"https:\/\/www.zenloop.com\/en\/wp-json\/wp\/v2\/media?parent=1749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}